{"id":1730,"date":"2009-05-24T11:44:55","date_gmt":"2009-05-24T02:44:55","guid":{"rendered":"http:\/\/www.color-lounge.com\/blog\/?p=1730"},"modified":"2010-10-02T23:18:46","modified_gmt":"2010-10-02T14:18:46","slug":"hong-kong-31-mars-2009","status":"publish","type":"post","link":"https:\/\/www.color-lounge.com\/blog\/2009\/hong-kong-31-mars-2009\/","title":{"rendered":"Hong Kong &#8211; 31 mars 2009"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.color-lounge.com\/blog\/wp-content\/uploads\/2009\/05\/hk347.jpg?w=640&#038;ssl=1\" alt=\"Fish market - Hong Kong\" \/><br \/>\n<strong>Septi\u00e8me jour<\/strong><br \/>\nC&rsquo;est avec un l\u00e9ger pincement au c\u0153ur que je passe cette derni\u00e8re journ\u00e9e compl\u00e8te \u00e0 Hong Kong, profitant de chaque instant qui passe sachant qu&rsquo;il est le dernier. [Le d\u00e9part est pour demain.]<br \/>\nIl devient donc important de savourer chaque d\u00e9tail, d&rsquo;observer ce d\u00e9cor pour s&rsquo;en impr\u00e9gner, s&rsquo;en souvenir et le reconna\u00eetre un jour si je reviens. Je me souviens de mon plaisir et ma fiert\u00e9 \u00e0 retrouver assez bien mon chemin la deuxi\u00e8me fois que je m&rsquo;en fus \u00e0 Hano\u00ef. M\u00eame apr\u00e8s plusieurs ann\u00e9es, je savais o\u00f9 j&rsquo;allais, je savais o\u00f9 \u00e9taient mes rep\u00e8res et pouvais retrouver mon chemin. Je retournerai sans aucun doute \u00e0 Hong Kong et j&rsquo;ai bien l&rsquo;intention de vivre la m\u00eame chose qu&rsquo;\u00e0 Hano\u00ef!<\/p>\n<p>Pour aujourd&rsquo;hui, visiter \u00e0 nouveau le quartier qui m&rsquo;a le plus marqu\u00e9, qui m&rsquo;a le plus plu: <em>Mong Kok<\/em> me parait donc clair. Je sais ce que je veux y faire, je sais que je vais le savourer. Et cette journ\u00e9e se fera seul.<br \/>\nC&rsquo;est donc la premi\u00e8re journ\u00e9e que Christelle et moi passons chacun de notre c\u00f4t\u00e9. \u00c0 notre grand \u00e9tonnement, nous ne nous sommes pas quitt\u00e9s pendant tout le s\u00e9jour. Tout de suite, d\u00e8s la premi\u00e8re journ\u00e9e, j&rsquo;ai compris que nous pourrions sans doute continuer les vacances ensemble. Il est vrai qu&rsquo;avant de partir, j&rsquo;avais voulu mettre les choses au clair avec elle. Connaissant ma fa\u00e7on de voyager, qu&rsquo;elle ne lui plairait peut-\u00eatre pas, j&rsquo;avais pr\u00e9f\u00e9r\u00e9 lui exposer, ne connaissant pas sa fa\u00e7on. J&rsquo;avais imagin\u00e9 qu&rsquo;elle serait plut\u00f4t cool, \u00e0 se reposer, profiter de l&rsquo;h\u00f4tel et se promener tranquillement mais pas \u00e0 barouder toute la journ\u00e9e dehors. Beaucoup de gens &#8211; et je les comprends &#8211; souhaitent se reposer, \u00eatre tranquilles pendant leurs vacances, \u00e0 leur rythme et non pas stress\u00e9 par un emploi du temps comme tout le reste de l&rsquo;ann\u00e9e. De plus, lorsque je voyage, je prends beaucoup de photos et ne souhaite pas me sentir attendu ce qui ne permet pas de photographier \u00e0 son rythme. C&rsquo;est une des raisons principale pour laquelle je voyage seul. Je n&rsquo;impose mon rythme \u00e0 personne et personne ne m&rsquo;impose le sien.<br \/>\nJe me trompais concernant Christelle. Cette jeune femme que je consid\u00e8re comme une petite s\u0153ur, cette jeune femme que j&rsquo;ai mari\u00e9e a une fa\u00e7on de voyager tr\u00e8s proche de la mienne. Jamais press\u00e9e, ne m&rsquo;attendant pas, allant se perdre dans des coins pour revenir ensuite, s&rsquo;arr\u00eatant o\u00f9 elle veut s&rsquo;arr\u00eater&#8230; une personne tr\u00e8s tol\u00e9rante et ouverte. D\u00e8s que nous prenions une pause dans un restaurant ou un caf\u00e9, je sortais mon cahier pour r\u00e9diger mon journal, aucune remarque. Au contraire, elle respectait mon travail et me r\u00e9p\u00e9tait qu&rsquo;elle avait h\u00e2te de le lire car pour une fois, elle ne le d\u00e9gusterait pas de la m\u00eame fa\u00e7on. Nous avons donc pass\u00e9 nos journ\u00e9es ensemble, \u00e0 discuter durant la matin\u00e9e ce que nous allions faire dans la journ\u00e9e. Mieux, souvent, cela correspondait \u00e0 ce que l&rsquo;autre voulait faire. En ce 31 mars donc, notre derni\u00e8re journ\u00e9e, nous n&rsquo;allions nous retrouver qu&rsquo;en d\u00e9but de soir\u00e9e, pour aller f\u00eater dignement notre s\u00e9jour autour d&rsquo;une \u00ab\u00a0grande\u00a0\u00bb table, puis de plusieurs verres.<br \/>\nLa raison principale de mon envie de retourner \u00e0 <em>Mong Kok<\/em> \u00e9tait le march\u00e9 aux poissons rouges. Il y en avait d&rsquo;ailleurs une autre mais malheureusement, je n&rsquo;aurais pas eu le temps. Il m&rsquo;aurait fallu une journ\u00e9e suppl\u00e9mentaire pour photographier les panneaux publicitaires de nuit, justement dans mon quartier ador\u00e9 car le soir o\u00f9 je l&rsquo;avais fait, je manquais de connaissances du terrain et ne savais pas suffisamment o\u00f9 aller pour en faire des clich\u00e9s r\u00e9ussis. Ce sera pour la prochaine fois.<br \/>\n<img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.color-lounge.com\/blog\/wp-content\/uploads\/2009\/05\/hk340.jpg?w=640&#038;ssl=1\" alt=\"Bus on Nathan road - Hong Kong\" \/><br \/>\nPour retourner dans ce quartier au nord de <em>Kowloon<\/em>, je prends bien s\u00fbr le bus. Le trajet est un peu long et me permets de profiter de <em>Nathan road<\/em> sur le si\u00e8ge avant du deuxi\u00e8me \u00e9tage, avec son spectacle en technicolor qui surpasse tous les \u00e9crans du monde quelque soit leur taille. Je me dirige donc vers le terminal des bus en prenant la promenade, en lorgnant sur la baie et l&rsquo;\u00eele de l&rsquo;autre c\u00f4t\u00e9 pour en profiter \u00e0 chaque pas. La m\u00e9t\u00e9o est encore nuageuse m\u00eame s&rsquo;il y a un peu plus d&rsquo;\u00e9claircies que les jours pr\u00e9c\u00e9dents (enfin si on compte, le soleil aura perc\u00e9 deux ou trois fois&#8230;) Le gros paquet de nuages g\u00e9n\u00e9r\u00e9 par la mousson au-dessus de la Chine continentale ne veut pas partir, tra\u00eene et recouvre pratiquement tout le territoire. Certes, nous n&rsquo;aurons eu qu&rsquo;une journ\u00e9e de pluie, mais j&rsquo;aurais bien aim\u00e9 un peu plus de contraste au niveau des couleurs&#8230; Je prends le bus num\u00e9ro 2 en faisant bien attention \u00e0 l&rsquo;arr\u00eat o\u00f9 je descends. Pour cela, je prends en photo le panneau des arr\u00eats car \u00e0 l&rsquo;int\u00e9rieur, l&rsquo;affichage des arr\u00eats n&rsquo;est qu&rsquo;en chinois. Je me rends compte rapidement, une fois \u00e0 l&rsquo;int\u00e9rieur, que les caract\u00e8res ne correspondent pas. Cela doit \u00eatre \u00e0 cause du chinois simplifi\u00e9 utilis\u00e9 pour le panneau \u00e9lectronique dans le bus. Mais justement parce que je commence \u00e0 avoir mes rep\u00e8res, je parviens \u00e0 descendre exactement l\u00e0 o\u00f9 je veux. Le bus file sur <em>Nathan road<\/em>. Certains panneaux publicitaires ne passent qu&rsquo;\u00e0 quelques centim\u00e8tres du toit. La r\u00e9glementation est pr\u00e9cise. La danse de ces <a title=\"ah la g\u00e9om\u00e9trie...\" href=\"http:\/\/mathworld.wolfram.com\/Cuboid.html\" target=\"_blank\">cubo\u00efdes<\/a> oblongs roulants est impressionnante. Ils sont tr\u00e8s nombreux sur cet axe central. Ils se doublent, s&rsquo;attendent \u00e0 un arr\u00eat, saute deux files d&rsquo;un coup de volant, se penchent dans les tournants&#8230; le tout dans un vrombissement des moteurs. Globalement, les engins sont r\u00e9cents et puissants. Ils sont confortables et construits avec de grandes fen\u00eatres. Il reste que les conducteurs au Japon, en France ou ailleurs sont de gentils petits nouveaux n\u00e9s \u00e0 c\u00f4t\u00e9 d&rsquo;ici. Il est absolument imp\u00e9ratif de ce tenir aux barres (g\u00e9n\u00e9ralement jaunes) qui sont partout dans le bus. On comprend leur emplacement rapidement et on le trouve efficace aussit\u00f4t. Peu importe si vous \u00eates debout, que vous venez de monter et que les portes se referment derri\u00e8re vous o\u00f9 vont bient\u00f4t s&rsquo;ouvrir: le conducteur d\u00e9marre, s&rsquo;arr\u00eate uniquement selon la circulation ou son itin\u00e9raire. La descente des escaliers en marche est tr\u00e8s p\u00e9rilleuse, surtout lorsque comme moi, vous avez du mat\u00e9riel photo qui vous encombre et vous occupe un bras. On peut descendre au dernier moment, lorsque le bus est \u00e0 son arr\u00eat mais gare \u00e0 vous si le chauffeur a d\u00e9cid\u00e9 de partir. Vous ne pourrez descendre qu&rsquo;\u00e0 l&rsquo;arr\u00eat suivant car il est d\u00e9j\u00e0 au milieu de la rue. Reste que l&rsquo;exp\u00e9rience est obligatoire, comme le tramway sur l&rsquo;\u00eele.<br \/>\n<iframe loading=\"lazy\" width=\"485\" height=\"350\" frameborder=\"0\" scrolling=\"no\" marginheight=\"0\" marginwidth=\"0\" src=\"http:\/\/maps.google.com\/maps?ie=UTF8&amp;t=h&amp;ll=22.320324,114.169225&amp;spn=0.001737,0.002602&amp;z=18&amp;output=embed\"><\/iframe><br \/>\nEnviron vingt minutes plus tard, je suis \u00e0 mon arr\u00eat <em>Fife street<\/em>, un peu apr\u00e8s <em>Argyle street<\/em>, des rues perpendiculaires \u00e0 <em>Nathan road<\/em>, des croisements \u00e0 l&rsquo;activit\u00e9 incessante. Pr\u00e9cis\u00e9ment, en bus, les croisements sont les plus jouissifs pour profiter du panorama: <em>Austin road<\/em>, <em>Jordan road<\/em>, <em>Waterloo road<\/em>, <em>Mong Kok road<\/em>&#8230; Nous sommes aux alentours de midi. Les magasins du march\u00e9 aux poissons ouvrent. Certains ne sont pas encore ouverts et quand je leur demande, ils m&rsquo;annoncent leurs horaires: Une heure! Je peux cependant commencer mon hommage \u00e0 <a title=\"Exposition solo\" href=\"https:\/\/www.color-lounge.com\/blog\/?p=1289\" target=\"_blank\">Mika Ninagawa<\/a>. En effet, je souhaite travailler sur les couleurs et le flou des poissons en mouvement. Je me concentre sur les plus color\u00e9s et ceux avec des <em>formes<\/em> des plus \u00e9tonnantes. Certains ont des protub\u00e9rances rouge vif au niveau de la t\u00eate, d&rsquo;autres de fines poches sur les cot\u00e9s de la gueule qui suivent leur d\u00e9placement avec un l\u00e9ger d\u00e9calage, comme lors d&rsquo;un choc o\u00f9 la r\u00e9action vient un peu apr\u00e8s l&rsquo;action. Ils font sourire et chaque personne qui les observe reste \u00e0 les contempler et \u00e0 s&rsquo;\u00e9merveiller des capacit\u00e9s de m\u00e8re Nature. Le ballet des poissons est d&rsquo;ailleurs captivant. Comme je souhaite le moins possible interrompre leur danse, j&rsquo;approche mon gros objectif tout doucement de la paroi de l&rsquo;aquarium et le colle d\u00e9licatement pour ne pas le cogner ce qui effraierait les poissons. D\u00e9j\u00e0, lorsqu&rsquo;ils voient cet \u00e9norme objet noir s&rsquo;approcher, ils s&rsquo;\u00e9loignent un peu, avant de continuer \u00e0 \u00e9voluer comme si de rien n&rsquo;\u00e9tait voyant l&rsquo;objet en question qui ne bouge plus. Le compteur de mon appareil d\u00e9file&#8230; Les vendeurs ne me disent rien alors que je suis en plein milieu du magasin, emp\u00eachant certainement des acheteurs potentiels d&rsquo;observer. Car je reste \u00e0 chaque fois assez longtemps. Je ne peux m&#8217;emp\u00eacher de penser que peut-\u00eatre, c&rsquo;est ici que Mika est venue prendre ses photos, que peut-\u00eatre ce m\u00eame vendeur a vu, il y a quelques ann\u00e9es, une japonaise faire la m\u00eame chose avec son appareil. Le compteur continue de d\u00e9filer. Je visite plusieurs magasins. Les couleurs de ces cyprins dor\u00e9s sur un fond sombre &#8211; noir, parfois bleu roi ou bleu marine &#8211; donne un tableau contrast\u00e9 absorbant.<br \/>\nAu milieu des magasins d&rsquo;animaux domestiques (car il n&rsquo;y a pas que des poissons dans le march\u00e9 aux poissons&#8230;), se trouve une boulangerie o\u00f9 je peux essayer le <a title=\"Wikipedia\" href=\"http:\/\/en.wikipedia.org\/wiki\/Pineapple_bun\" target=\"_blank\"><em>pain \u00e0 l&rsquo;ananas<\/em><\/a>. <em>Euh il est o\u00f9 l&rsquo;ananas l\u00e0-dedans? Il n&rsquo;y en a pas? Ah c&rsquo;est normal?! Bon&#8230;<\/em> Et oui, il en a seulement la forme. La croute de sucre sur le dessus est cens\u00e9 rappeler l&rsquo;ananas par sa forme. Cela se mange facilement. Plus tard, je veux absolument manger une derni\u00e8re fois &#8211; sur place et pour cette fois-ci &#8211;  la cuisine vapeur que j&rsquo;aime tant. Je ne suis pas loin du restaurant o\u00f9 nous sommes all\u00e9s la premi\u00e8re fois que nous \u00e9tions \u00e0 <em>Mong Kok<\/em>, le 28 mars. M\u00eame au milieu de l&rsquo;apr\u00e8s-midi, le restaurant est en pleine activit\u00e9. Les serveurs me reconnaissent ainsi que la responsable de l&rsquo;autre jour. Je m&rsquo;assieds tranquillement \u00e0 une table, au milieu  des locaux. Je commande des <a title=\"Wikipedia\" href=\"http:\/\/en.wikipedia.org\/wiki\/Xiaolongbao\" target=\"_blank\">bouch\u00e9s vapeur<\/a> et des <a title=\"Wikipedia\" href=\"http:\/\/en.wikipedia.org\/wiki\/Char_siu_baau\" target=\"_blank\">pains vapeur<\/a> avant de me plonger dans la r\u00e9daction de mon journal. Comme \u00e0 l&rsquo;habitude, cela ne manque pas, les serveurs et serveuses passent presque tous les uns apr\u00e8s les autres pour voir, par-dessus mon \u00e9paule, ce que je suis entrain d&rsquo;\u00e9crire pendant ces longues minutes dans mon cahier. Suis-je un critique gastronomique?<br \/>\nJ&rsquo;observe une femme d&rsquo;un certain \u00e2ge qui vient de s&rsquo;installer \u00e0 la table voisine. Elle est seule. Elle ouvre le menu, le pose sur la table et verse du th\u00e9 dans sa tasse, y trempe ses baguettes et sa cuill\u00e8re avant de vers\u00e9 le th\u00e9 utilis\u00e9 dans un bol que vient de lui apporter un serveur. Rite? Manie? Le serveur que j&rsquo;interroge sur le pourquoi de ses actions est g\u00ean\u00e9 par ma questions et me r\u00e9ponds nerveusement un \u00ab\u00a0Mais tout est tr\u00e8s propre ici!\u00a0\u00bb ce qui n&rsquo;est pas du tout ma question. D\u00e9cid\u00e9ment, \u00e7a ne passe pas&#8230; Je le rassure et il finit par me dire qu&rsquo;elle doit trouver que c&rsquo;est sale. Manie donc&#8230;<br \/>\n<img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.color-lounge.com\/blog\/wp-content\/uploads\/2009\/05\/hk344.jpg?w=640&#038;ssl=1\" alt=\"Streets in Mong Kok - Hong Kong\" \/><br \/>\nApr\u00e8s le d\u00e9jeuner, je tiens \u00e0 prendre une autre s\u00e9rie de photo: des sc\u00e8nes de rue. Je sens que je n&rsquo;en ai pas assez pris depuis mon arriv\u00e9e et je d\u00e9sire saisir un quotidien, un moment ordinaire de la vie hongkongaise. <em>Mong Kok<\/em> est en cela parfait. M\u00eame si je suis souvent rep\u00e9r\u00e9, je me place \u00e0 un endroit et n&rsquo;en bouge plus. \u00c0 c\u00f4t\u00e9 d&rsquo;un poteau \u00e0 l&rsquo;angle d&rsquo;une rue, au feu rouge d&rsquo;<em>Argyle street<\/em> avec <em>Tung Choi street<\/em>, devant un magasin. Apr\u00e8s celui des poissons, un autre ballet s&rsquo;op\u00e8re dans la ville avec les bip\u00e8des qui se faufilent dans la foule, attendent un feu qui passe au vert, regardent en l&rsquo;air, s&#8217;embrassent, baillent, t\u00e9l\u00e9phonent&#8230; ils sont fascinants. Le compteur n&rsquo;en finit pas de d\u00e9filer. Je pourrais rester l\u00e0 des heures durant \u00e0 \u00e9tudier l&rsquo;assistance pour trouver la personne \u00e0 photographier au moment o\u00f9 elle approche.<\/p>\n<p>Avant d&rsquo;aller retrouver Christelle pour la soir\u00e9e, je vais me poser dans un caf\u00e9 et essaie le tr\u00e8s haut b\u00e2timent du centre commercial <a title=\"Site officiel\" href=\"http:\/\/www.langhamplace.com.hk\/eng\/mall.php\" target=\"_blank\"><em>Langham place<\/em><\/a>. L&rsquo;espace &#8211; moderne &#8211; est int\u00e9ressant avec son immense escalator au milieu du hall du quatri\u00e8me \u00e9tage. Je monte bien \u00e9videmment tout en haut et y trouve un endroit agr\u00e9able. Je continue de gribouiller mon cahier jusqu&rsquo;\u00e0 l&rsquo;heure de prendre le bus pour retourner \u00e0 l&rsquo;h\u00f4tel. Dernier voyage dans ce moyen de transport.<br \/>\nChristelle est d\u00e9j\u00e0 dans la chambre. Je me change afin d&rsquo;\u00eatre <em>habill\u00e9<\/em> pour la soir\u00e9e. Nous allons une derni\u00e8re fois sur l&rsquo;\u00eele pour enfin monter sur le <a title=\"Site officiel\" href=\"http:\/\/www.thepeak.com.hk\/en\/\" target=\"_blank\"><em>Mont Victoria<\/em><\/a>.<\/p>\n<p>Dans le hall de l&rsquo;h\u00f4tel, je passe \u00e0 la r\u00e9ception voir Cherry afin de lui demander de prendre son portrait ce qu&rsquo;elle accepte m\u00eame s&rsquo;il y a du monde. Elle me donne son adresse email afin que je lui envoie le clich\u00e9 une fois retravaill\u00e9. J&rsquo;eusse aim\u00e9 discut\u00e9 davantage avec elle mais elle est en plein travail et les clients n&rsquo;en finissent pas d&rsquo;arriver \u00e0 l&rsquo;accueil. <em>Vous pouviez pas choisir un autre moment pour venir non?!<\/em> Nous nous dirigeons ensuite vers le ferry, il est environ 18h30. La houle est assez forte et remue le bateau jusqu&rsquo;\u00e0 l&#8217;embarcad\u00e8re de l&rsquo;autre c\u00f4t\u00e9 de la baie. Il y a d&rsquo;ailleurs un tel tangage que la passerelle est relev\u00e9e et nous devons attendre. Le risque de glisser ou perdre l&rsquo;\u00e9quilibre  existe au moment de d\u00e9barquer en raison des mouvements de la passerelle. Ce soir, le risque est trop grand aussi les matelots nous arr\u00eatent d&rsquo;un geste de la main &#8211; certains passagers sont descendus &#8211; et rel\u00e8vent le chemin pour d\u00e9barquer. Le ferry se comporte effectivement comme un bouchon sur l&rsquo;eau et il faut se tenir pour ne pas risquer de se cogner ou pire, tomber. L&rsquo;exp\u00e9rience nous amuse beaucoup et nous sommes tr\u00e8s heureux de la vivre, asseyant un peu plus notre exp\u00e9rience et notre connaissance de la ville. Nous prenons apr\u00e8s le bus 15C qui relie le port \u00e0 la station du <a title=\"Site officiel\" href=\"http:\/\/www.thepeak.com.hk\/en\/5_5_1.asp\" target=\"_blank\"><em>Peak tram<\/em><\/a>. Monter \u00e0 pied rel\u00e8ve du d\u00e9fi et puis quand on voyage, prendre diff\u00e9rents transports est une obligation. Bon, comme nous sommes un peu en retard, \u00e7a nous permettra aussi de limiter les d\u00e9g\u00e2ts. J&rsquo;ai r\u00e9serv\u00e9 deux jours plus t\u00f4t pour 19h. La r\u00e9servation est n\u00e9cessaire pour ce lieu fameux avec sa vue. Le tram est mignon mais moins authentique que le ferry \u00e0 mon go\u00fbt. L&rsquo;exp\u00e9rience est par contre tr\u00e8s amusante. Rappelez-vous le moment o\u00f9 les montagnes russes commencent leur ascension. Vous avez exactement la m\u00eame sensation ici. Les passagers sont coll\u00e9s au dossier tellement la d\u00e9nivel\u00e9e est importante. On sent le c\u00e2ble qui nous tire vers le haut. Tout le monde est euphorique, tourne la t\u00eate dans tous les sens pour la vue, pour notre position par rapport aux immeubles voisins. Par moment, on ne doit pas \u00eatre loin d&rsquo;un angle \u00e0 45\u00b0. le tarif est plut\u00f4t \u00e9lev\u00e9 (22HK$ soit 2,2\u20ac) mais ils les valent compl\u00e8tement puisqu&rsquo;on s&rsquo;amuse et que c&rsquo;est le meilleur moyen pour atteindre le sommet. \u00c0 la derni\u00e8re station, on arrive par un couloir de boutique de souvenirs dont on se passerait bien.<br \/>\n<img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.color-lounge.com\/blog\/wp-content\/uploads\/2009\/05\/hk381.jpg?w=640&#038;ssl=1\" alt=\"Streets in Mong Kok - Hong Kong\" \/><br \/>\nLe restaurant se trouve dans un b\u00e2timent \u00e0 c\u00f4t\u00e9 de <a title=\"Site officiel\" href=\"http:\/\/www.thepeak.com.hk\/en\/home.asp\" target=\"_blank\"><em>The peak tower<\/em><\/a>, <a title=\"Wikipedia\" href=\"http:\/\/en.wikipedia.org\/wiki\/Peak_Galleria\" target=\"_blank\"><em>The peak galleria<\/em><\/a>, \u00e0 deux minutes. Il s&rsquo;agit en fait de centres commerciaux. On va au <a title=\"Site officiel\" href=\"http:\/\/www.cafedecogroup.com\/index.php?_topRm=1&amp;group=restaurants\" target=\"_blank\"><em>Cafe deco<\/em><\/a> &#8211; recommand\u00e9 par le Routard &#8211; pour sa vue, pas particuli\u00e8rement pour sa cuisine &#8211; certes correcte &#8211; mais qui n&rsquo;a rien de local, ni m\u00eame de chinoise. 99% des clients &#8211; \u00e9trangers &#8211; fr\u00e9missent de bonheur d&rsquo;\u00eatre l\u00e0, avec leurs amis, en couple, pour une occasion sp\u00e9ciale devant la baie vitr\u00e9e. La table qu&rsquo;on nous propose est incroyable. Il y a deux tables pour avoir la meilleure vue possible sur la baie, nous sommes \u00e0 l&rsquo;une des deux. En chemin, je demande \u00e0 la r\u00e9ceptionniste:<br \/>\n<em>&#8211; Vous nous avez choisi une bonne table j&rsquo;esp\u00e8re!<br \/>\n&#8211; La meilleure table du restaurant monsieur, la mieux plac\u00e9e.<\/em><br \/>\nNous n&rsquo;en croyons pas nos yeux. Coll\u00e9s \u00e0 la vitre, nous passons la soir\u00e9e riv\u00e9s vers les immeubles qui s&rsquo;illuminent \u00e0 20h pour <em>Symphony of lights<\/em>. D&rsquo;ici, d&rsquo;ailleurs, le spectacle est moins impressionnant. Nous sommes un peu trop loin et trop haut et il reste d\u00e9finitivement plus int\u00e9ressant quand on le regarde de <em>Kowloon<\/em>. Il n&rsquo;y a que les tables de la terrasse pour vaincre ce meilleur emplacement. Il fait encore trop frais et le vent est tr\u00e8s fort aujourd&rsquo;hui, ce qui influence aussi l&rsquo;acc\u00e8s \u00e0 l&rsquo;ext\u00e9rieur. Nos premiers cocktails &#8211; color\u00e9s &#8211; \u00e0 la main, nous trinquons avec un immense sourire pour f\u00eater nos vacances. Nous terminons en beaut\u00e9. Le dernier soir est pour moi l&rsquo;heure des bilans aussi travaill\u00e9-je un peu Christelle pour savoir ce qu&rsquo;elle a pens\u00e9 de son s\u00e9jour, de son premier voyage en Asie, en dehors du Japon. Elle est aux anges. Nous faisons aussi le bilan de nos journ\u00e9es ensemble, de la fa\u00e7on dont nous les avons v\u00e9cues. Le bilan est tr\u00e8s positif car il y a bien eu un \u00e9change r\u00e9ciproque. Nous discutons \u00e0 b\u00e2tons rompus pendant que la danse des plats se d\u00e9roule: une assiette d&rsquo;entr\u00e9es vari\u00e9es (vietnamienne\/asiatique), un poulet tandorii (indien) accompagn\u00e9 de naan (indien), du vin rouge (languedocien), du vin blanc (allemand), un fondant au chocolat (occidental?), un sunday (am\u00e9ricain)&#8230; Nous jurons de redescendre \u00e0 pied pour br\u00fbler des calories tellement nous sommes repus. L&rsquo;endroit se donne des allures de grands restaurant et propose le service d&rsquo;un Monsieur lavabo &#8211; en veste blanche &#8211; qui &#8211; dans les toilettes &#8211; ouvre les robinets, appuie sur le dispenseur de savon, tend des papiers absorbants pour s&rsquo;essuyer&#8230; Bon, je doute de l&rsquo;utilit\u00e9 mais apr\u00e8s tout&#8230; Lorsque je m&rsquo;y rends la premi\u00e8re fois &#8211; n&rsquo;ayant pas envisag\u00e9 la chose dans un restaurant qui me semble modeste &#8211; je n&rsquo;ai aucun pourboire \u00e0 lui remettre et en suis d\u00e9sol\u00e9<br \/>\n<em>&#8211; Ok sir, ok! No problem, no problem! Ok sir!<\/em><br \/>\nLorsque j&rsquo;y retourne la deuxi\u00e8me fois, je pr\u00e9pare une pi\u00e8ce pour lui montrer que j&rsquo;ignorais sa pr\u00e9sence la derni\u00e8re fois et que je tiens \u00e0 r\u00e9parer mon erreur. M\u00eame man\u00e8ge sauf l&rsquo;am\u00e9ricain qui me pr\u00e9c\u00e8de et qui lui sort un billet de 20HK$&#8230; j&rsquo;en h\u00e9site \u00e0 sortir ma pi\u00e8ce ridicule de 5HK$&#8230; remonte ma pauvre fiert\u00e9 et lui tend le plus d\u00e9licatement possible en esp\u00e9rant qu&rsquo;il ne verra pas la mis\u00e8re bon march\u00e9 que je lui donne, penaud.<br \/>\n<em>&#8211; Ok sir, ok! Thank you, no problem! Ok sir!<\/em><br \/>\nAh tiens, il y a une variante&#8230;<\/p>\n<p>Nous quittons le <em>Cafe deco<\/em> trois heures et demie plus tard avec une bonne note d&rsquo;environ 1000HK$ (soit 100\u20ac) pour deux. La table \u00e0 c\u00f4t\u00e9 (5 Fran\u00e7ais et une hongkongaise) avec leurs deux bouteilles de champagne et trois de vins doivent pour en avoir une l\u00e9g\u00e8rement plus sal\u00e9e&#8230; Je souhaite faire quelques photos du panorama avant de redescendre. Je demande \u00e0 une jeune femme accompagn\u00e9e s&rsquo;il faut du temps pour le trajet \u00e0 pied. Elle me regarde comme si je lui avais demand\u00e9 comment on fait les b\u00e9b\u00e9s.<br \/>\n<em>&#8211; C&rsquo;est trop loin! Peut-\u00eatre trois heures!<br \/>\n&#8211; Trois heures?!<br \/>\n&#8211; Oui et puis c&rsquo;est dangereux!<br \/>\n&#8211; Dangereux?! Mais pourquoi?<\/em><br \/>\nElle interpelle son ami.<br \/>\n<em>&#8211; Il veut descendre \u00e0 pied. C&rsquo;est impossible non?<br \/>\n&#8211; Ouh la&#8230; impossible!<br \/>\n&#8211; Mais vous pouvez descendre jusqu&rsquo;\u00e0 la prochaine station du tram. L\u00e0, ce n&rsquo;est pas loin.<br \/>\n&#8211; Euh&#8230; d&rsquo;accord, merci.<\/em><br \/>\nDangereux?&#8230; Je veux marcher en raison du poids sur mon ventre. La promenade digestive est n\u00e9cessaire! Nous prenons le chemin. D\u00e9j\u00e0, la vue s&rsquo;am\u00e9liore. A peine 50 pas plus bas, le panorama est encore plus grand et plus beau car nous nous sommes d\u00e9j\u00e0 rapproch\u00e9s. De plus, le tram passe juste en dessous et on peut le voir. La d\u00e9nivel\u00e9 est tr\u00e8s impressionnante. On franchit plusieurs centim\u00e8tres \u00e0 chaque pas. Tr\u00e8s vite, nous voyons la station puis deux maisons. Ouaaaah, mais qui peut habiter l\u00e0? Un gardien s&rsquo;approche de nous et je lui demande confirmation sur le temps et le risque de l&rsquo;exp\u00e9dition.<br \/>\n<em>&#8211; Jusqu&rsquo;\u00e0 <\/em>Central<em>? Ooooh trente minutes.<br \/>\n&#8211; Trente minutes?!<br \/>\n&#8211; Et c&rsquo;est dangereux?<br \/>\n&#8211; Mais non, regardez, c&rsquo;est ce chemin.<\/em><br \/>\nIl nous montre une rue goudronn\u00e9e abrupte mais tout \u00e0 fait praticable et \u00e9clair\u00e9e.<br \/>\n<em>&#8211; Si vous voulez, \u00e0 mi-chemin, vous arrivez dans une rue et l\u00e0, il y a des taxis qui passent souvent.<br \/>\n&#8211; Il faut combien de temps?<br \/>\n&#8211; Ooooh dix minutes.<br \/>\n&#8211; Dix minutes?! Allez, on est parti!<\/em><br \/>\nIl n&rsquo;y a donc aucun probl\u00e8me mais j&rsquo;ai rarement pris un chemin avec une telle d\u00e9nivel\u00e9e. C&rsquo;est par moment spectaculaire. Nous rions aux \u00e9clats de cette aventure. Nous ne croisons personne &#8211; nous apercevons de loin une femme qui prom\u00e8ne son chien &#8211; qui fait ce trajet. S&rsquo;il est infernal \u00e0 monter, le contraire est plut\u00f4t amusant. D&rsquo;autant qu&rsquo;on se rapproche de la ville \u00e0 grande vitesse, qu&rsquo;on passe juste \u00e0 c\u00f4t\u00e9 des tours d&rsquo;habitation qui se cachent derri\u00e8re les arbres. La vue est tout aussi int\u00e9ressante. Peu de temps apr\u00e8s \u00eatre arriv\u00e9s sur la route, un taxi passe. Je le h\u00e8le et Christelle me f\u00e9licite car elle vient de regarder sa montre. Il est 23h10 et le dernier ferry par \u00e0 23h30. Nous n&rsquo;avons plus le temps. Croyant avoir pratiquement tout descendu, nous d\u00e9couvrons en fait que le taxi n&rsquo;en finit pas de d\u00e9valer des pentes jusqu&rsquo;\u00e0 <em>Queen&rsquo;s road<\/em>. La voiture plonge vers le centre de la terre. Sur le si\u00e8ge arri\u00e8re en cuir, nous devons caler nos pieds sur les si\u00e8ges avant et nous tenir fermement \u00e0 la poign\u00e9e pour ne pas glisser. Alors que j&rsquo;appuie v\u00e9ritablement sur mes jambes pour ne pas d\u00e9raper davantage &#8211; je suis \u00e0 la moiti\u00e9 de la baquette &#8211; Christelle a d\u00e9j\u00e0 les fesses sur le bord, pr\u00eate \u00e0 tomber. Elle bafouille en disant \u00ab\u00a0J&rsquo;vais tomber! Quand est-ce que \u00e7a s&rsquo;arr\u00eate?!\u00a0\u00bb Eclats de rire! Notre promenade <em>digestive<\/em> est un succ\u00e8s! Vive l&rsquo;aventure!<br \/>\n<img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.color-lounge.com\/blog\/wp-content\/uploads\/2009\/05\/hk376.jpg?w=640&#038;ssl=1\" alt=\"Star ferry - bay - Hong Kong\" \/><br \/>\nNous arrivons \u00e0 temps pour la derni\u00e8re travers\u00e9e. Assis sur les bancs en bois vernis, les pulsations du moteur qui traversent le corps, nous restons tr\u00e8s silencieux. Profiter du ferry, profiter de la vue&#8230; profiter de cette derni\u00e8re travers\u00e9e. Je ressens dans l&rsquo;air notre besoin de nous impr\u00e9gner l&rsquo;un comme l&rsquo;autre de ce que nous vivons \u00e0 ce moment-l\u00e0. Nous aimons Hong Kong et nous allons la quitter.<\/p>\n<p>Nous retournons \u00e0 l&rsquo;h\u00f4tel rapidement pour poser tout mon mat\u00e9riel photo bien trop lourd. Nous resortons aussit\u00f4t pour terminer la soir\u00e9e dans des bars de <em>Minden avenue<\/em>, d\u00e9couverts la veille. Le club nous invite \u00e0 rentrer car il y a tr\u00e8s peu de clients, ce qui se comprend un mardi soir. C&rsquo;est d&rsquo;ailleurs le <em>Special ladies night<\/em> ou tout est gratuit pour les femmes: entr\u00e9e et boissons \u00e0 volont\u00e9! Cependant, nous sommes plus dans l&rsquo;id\u00e9e de profiter d&rsquo;endroits pour prendre un verre et discuter. Nous essayons <em>Cloudenine <\/em>\u00e0 l&rsquo;entr\u00e9e particuli\u00e8re puis <em>Club A<\/em> car j&rsquo;avais un peu discut\u00e9 avec un des membre hier. Je fais confiance aux barmen pour nous pr\u00e9parer des cocktails qui sont r\u00e9ussis. Deux heures du matin \u00e0 Hong Kong, la journ\u00e9e &#8211; \u00e0 l&rsquo;image de notre s\u00e9jour &#8211; fut riche et intense.<\/p>\n<p>Il nous reste quelques heures demain matin pour faire quelques achats.<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/feedburner.google.com\/fb\/a\/mailverify?uri=ColorLounge&amp;loc=fr_FR\">Inscription au blog Color Lounge par email<\/a><\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<\/p>\n<p>Voici la galerie de photos du 31 mars.<br \/>\nDeux th\u00e8mes principaux: les bip\u00e8des et les <a title=\"Wikipedia\" href=\"http:\/\/fr.wikipedia.org\/wiki\/Poisson_rouge\" target=\"_blank\">cyprinid\u00e9s<\/a>. J&rsquo;esp\u00e8re que le mariage vous amusera.<br \/>\n1 panorama pour cette journ\u00e9e: le centre commercial Langham &#8211; 8 images<\/p>\n<p>Passez votre souris sur la droite des photos de la galerie et cliquez pour voir la suivante.<\/p>\nngg_shortcode_0_placeholder\n","protected":false},"excerpt":{"rendered":"<p>Septi\u00e8me jour C&rsquo;est avec un l\u00e9ger pincement au c\u0153ur que je passe cette derni\u00e8re journ\u00e9e compl\u00e8te \u00e0 Hong Kong, profitant de chaque instant qui passe sachant qu&rsquo;il est le dernier. [Le d\u00e9part est pour demain.] Il devient donc important de savourer chaque d\u00e9tail, d&rsquo;observer ce d\u00e9cor pour s&rsquo;en impr\u00e9gner, s&rsquo;en souvenir et le reconna\u00eetre un [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[13],"tags":[2505,2511,2504,2493],"class_list":["post-1730","post","type-post","status-publish","format-standard","hentry","category-voyages","tag-chine","tag-hong-kong","tag-journal-de-voyage","tag-photographie"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5BAbw-rU","_links":{"self":[{"href":"https:\/\/www.color-lounge.com\/blog\/wp-json\/wp\/v2\/posts\/1730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.color-lounge.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.color-lounge.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.color-lounge.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.color-lounge.com\/blog\/wp-json\/wp\/v2\/comments?post=1730"}],"version-history":[{"count":22,"href":"https:\/\/www.color-lounge.com\/blog\/wp-json\/wp\/v2\/posts\/1730\/revisions"}],"predecessor-version":[{"id":2938,"href":"https:\/\/www.color-lounge.com\/blog\/wp-json\/wp\/v2\/posts\/1730\/revisions\/2938"}],"wp:attachment":[{"href":"https:\/\/www.color-lounge.com\/blog\/wp-json\/wp\/v2\/media?parent=1730"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.color-lounge.com\/blog\/wp-json\/wp\/v2\/categories?post=1730"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.color-lounge.com\/blog\/wp-json\/wp\/v2\/tags?post=1730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}